{"id":31642,"date":"2025-05-17T14:42:13","date_gmt":"2025-05-17T18:42:13","guid":{"rendered":"https:\/\/knowledgeflow.org\/?page_id=31642"},"modified":"2025-05-17T14:45:39","modified_gmt":"2025-05-17T18:45:39","slug":"newsletter-sign-up","status":"publish","type":"page","link":"https:\/\/knowledgeflow.org\/zh\/newsletter-sign-up\/","title":{"rendered":"\u8ba2\u9605\u65f6\u4e8b\u901a\u8baf"},"content":{"rendered":"<style>.wp-block-kadence-advancedheading.kt-adv-heading31642_cc23cd-4b, .wp-block-kadence-advancedheading.kt-adv-heading31642_cc23cd-4b[data-kb-block=\"kb-adv-heading31642_cc23cd-4b\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading31642_cc23cd-4b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading31642_cc23cd-4b[data-kb-block=\"kb-adv-heading31642_cc23cd-4b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading31642_cc23cd-4b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading31642_cc23cd-4b[data-kb-block=\"kb-adv-heading31642_cc23cd-4b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading31642_cc23cd-4b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading31642_cc23cd-4b\">Newsletter Sign up<\/h2>\n\n\n<style>.kb-row-layout-id31642_e3829d-0c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id31642_e3829d-0c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id31642_e3829d-0c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id31642_e3829d-0c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id31642_e3829d-0c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id31642_e3829d-0c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id31642_e3829d-0c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column31642_9771af-a3 > .kt-inside-inner-col,.kadence-column31642_9771af-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column31642_9771af-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column31642_9771af-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column31642_9771af-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column31642_9771af-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column31642_9771af-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column31642_9771af-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column31642_9771af-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column31642_9771af-a3\"><div class=\"kt-inside-inner-col\"><style>.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-31642_1099ef-4e kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_31642_1099ef-4e_0\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_0\" id=\"kb_field_31642_1099ef-4e_0\" data-label=\"Email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-0\" data-required=\"yes\"\/><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"31642_1099ef-4e\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"31642\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">\u8bf7\u5728\u6d4f\u89c8\u5668\u4e2d\u542f\u7528 JavaScript \u4ee5\u63d0\u4ea4\u8868\u5355<\/div><style>.kadence-form-31642_1099ef-4e .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n\n<style>.kadence-column31642_e17b86-62 > .kt-inside-inner-col,.kadence-column31642_e17b86-62 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column31642_e17b86-62 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column31642_e17b86-62 > .kt-inside-inner-col{flex-direction:column;}.kadence-column31642_e17b86-62 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column31642_e17b86-62 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column31642_e17b86-62{position:relative;}@media all and (max-width: 1024px){.kadence-column31642_e17b86-62 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column31642_e17b86-62 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column31642_e17b86-62\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u8ba2\u9605\u65f6\u4e8b\u901a\u8baf<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-31642","page","type-page","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"sdkgone0893","author_link":"https:\/\/knowledgeflow.org\/zh\/author\/colin_lqi4fpdv\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/pages\/31642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/comments?post=31642"}],"version-history":[{"count":5,"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/pages\/31642\/revisions"}],"predecessor-version":[{"id":31648,"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/pages\/31642\/revisions\/31648"}],"wp:attachment":[{"href":"https:\/\/knowledgeflow.org\/zh\/wp-json\/wp\/v2\/media?parent=31642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}