{"id":34377,"date":"2025-11-22T16:07:56","date_gmt":"2025-11-22T21:07:56","guid":{"rendered":"https:\/\/knowledgeflow.org\/?post_type=resource&#038;p=34377"},"modified":"2025-11-24T13:23:56","modified_gmt":"2025-11-24T18:23:56","slug":"cybersafety-by-design-7-critical-principles","status":"publish","type":"resource","link":"https:\/\/knowledgeflow.org\/fr\/resource\/cybersafety-by-design-7-critical-principles\/","title":{"rendered":"Cybers\u00e9curit\u00e9 d\u00e8s la conception - 7 principes essentiels"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Cybers\u00e9curit\u00e9 par conception pour les organismes sans but lucratif<\/strong> a \u00e9t\u00e9 d\u00e9velopp\u00e9 par KnowledgeFlow en 2022 comme un cadre pratique pour aider les organisations \u00e0 cr\u00e9er des programmes num\u00e9riques plus s\u00fbrs et plus respectueux de la vie priv\u00e9e. Les principes \u00e9nonc\u00e9s dans ce document s'inspirent du travail de longue date de notre fondateur, Claudiu Popa, aupr\u00e8s du Commissariat \u00e0 l'information et \u00e0 la protection de la vie priv\u00e9e de l'Ontario, notamment de sa contribution \u00e0 l'\u00e9volution de <strong>Confidentialit\u00e9 d\u00e8s la conception<\/strong> et le plus r\u00e9cent <strong>Confidentialit\u00e9 par ReDesign<\/strong> initiatives. Ces liens constituent une base solide pour les organisations qui souhaitent appliquer des principes reconnus en mati\u00e8re de confidentialit\u00e9 de mani\u00e8re moderne, concr\u00e8te et adapt\u00e9e aux environnements num\u00e9riques actuels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette ressource adapte ces concepts bien \u00e9tablis en mati\u00e8re de confidentialit\u00e9 \u00e0 <strong>Sept principes de cybers\u00e9curit\u00e9 d\u00e8s la conception<\/strong>, sp\u00e9cialement con\u00e7u pour les organisations \u00e0 but non lucratif, les \u00e9coles et toute organisation travaillant avec des enfants, des jeunes, des familles ou d'autres communaut\u00e9s vuln\u00e9rables. L'accent est mis sur des mesures de protection pratiques qui r\u00e9duisent le risque d'atteintes \u00e0 la vie priv\u00e9e, d'abus en ligne, de surveillance, d'exploitation et d'autres pr\u00e9judices, tout en favorisant des exp\u00e9riences num\u00e9riques positives et engageantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l'int\u00e9rieur, les organisations trouveront :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une explication claire de la <strong>7 Principes de cybers\u00e9curit\u00e9 d\u00e8s la conception<\/strong> et comment ils s'appliquent aux programmes et plateformes du monde r\u00e9el <\/li>\n\n\n\n<li>A <strong>Liste de contr\u00f4le des risques li\u00e9s \u00e0 la cybers\u00e9curit\u00e9 (CRC)<\/strong> pour \u00e9valuer les outils, les applications, les sites Web et les technologies d'apprentissage <\/li>\n\n\n\n<li>Un pratique <strong>D\u00e9tecter \u2013 Corriger \u2013 Surveiller<\/strong> mod\u00e8le visant \u00e0 renforcer les contr\u00f4les continus en mati\u00e8re de confidentialit\u00e9 et de s\u00e9curit\u00e9 <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces outils peuvent \u00eatre utilis\u00e9s par :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Commissions scolaires<\/strong> conception ou \u00e9valuation des technologies destin\u00e9es aux \u00e9tudiants<\/li>\n\n\n\n<li><strong>Organismes \u00e0 but non lucratif venant en aide aux enfants, aux jeunes, aux personnes \u00e2g\u00e9es ou aux nouveaux arrivants<\/strong><\/li>\n\n\n\n<li><strong>Organisations communautaires<\/strong> cr\u00e9ation de services num\u00e9riques ou de programmes en ligne<\/li>\n\n\n\n<li><strong>Tout groupe responsable des informations personnelles<\/strong>, en particulier impliquant des mineurs<\/li>\n<\/ul>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/knowledgeflow.org\/wp-content\/uploads\/2025\/11\/knowledgeflow-nonprofit-resource-cybersafety-by-design.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu int\u00e9gr\u00e9 knowledgeflow-nonprofit-resource-cybersafety-by-design.\"><\/object><a id=\"wp-block-file--media-0a5e7d1a-b3cb-4d20-a163-65daaf297aa3\" href=\"https:\/\/knowledgeflow.org\/wp-content\/uploads\/2025\/11\/knowledgeflow-nonprofit-resource-cybersafety-by-design.pdf\">knowledgeflow-ressource-\u00e0-but-non-lucratif-cybers\u00e9curit\u00e9-d\u00e8s-la-conception<\/a><a href=\"https:\/\/knowledgeflow.org\/wp-content\/uploads\/2025\/11\/knowledgeflow-nonprofit-resource-cybersafety-by-design.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-0a5e7d1a-b3cb-4d20-a163-65daaf297aa3\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fondant la cybers\u00e9curit\u00e9 sur des cadres reconnus en mati\u00e8re de protection de la vie priv\u00e9e, l'approche proactive et ax\u00e9e sur l'att\u00e9nuation des risques de la PbD et l'accent mis par la PbRD sur la refonte des syst\u00e8mes afin de combler les lacunes existantes, cette ressource aide les organisations \u00e0 adopter une approche coh\u00e9rente, moderne et fiable pour prot\u00e9ger les personnes qu'elles servent.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cybersafety by Design for Non-Profits a \u00e9t\u00e9 d\u00e9velopp\u00e9 par KnowledgeFlow en 2022 comme un cadre pratique pour aider les organisations \u00e0 renforcer la s\u00e9curit\u00e9,\u2026<\/p>","protected":false},"featured_media":18194,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"resource-type":[547],"topic":[540,544],"resource-initiative":[],"class_list":["post-34377","resource","type-resource","status-publish","format-standard","has-post-thumbnail","hentry","resource-type-guides","topic-online-privacy-and-security","topic-online-safety-for-children-and-parents"],"acf":[],"taxonomy_info":{"resource-type":[{"value":547,"label":"Guidebooks"}],"topic":[{"value":540,"label":"Online Privacy and Security"},{"value":544,"label":"Online Safety for Children and Parents"}]},"featured_image_src_large":["https:\/\/knowledgeflow.org\/wp-content\/uploads\/2023\/04\/Guidebooks-Featured-Image-1024x256.png",1024,256,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/resource\/34377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/types\/resource"}],"version-history":[{"count":1,"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/resource\/34377\/revisions"}],"predecessor-version":[{"id":34380,"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/resource\/34377\/revisions\/34380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/media\/18194"}],"wp:attachment":[{"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/media?parent=34377"}],"wp:term":[{"taxonomy":"resource-type","embeddable":true,"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/resource-type?post=34377"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/topic?post=34377"},{"taxonomy":"resource-initiative","embeddable":true,"href":"https:\/\/knowledgeflow.org\/fr\/wp-json\/wp\/v2\/resource-initiative?post=34377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}